{"id":2159,"date":"2024-12-06T15:46:28","date_gmt":"2024-12-06T18:46:28","guid":{"rendered":"https:\/\/www.bomprincipioalimentos.com.br\/site\/?post_type=produtos&#038;p=2159"},"modified":"2025-03-05T17:18:25","modified_gmt":"2025-03-05T20:18:25","slug":"recheio-de-abacaxi","status":"publish","type":"produtos","link":"https:\/\/www.bomprincipioalimentos.com.br\/site\/produtos\/recheio-de-abacaxi\/","title":{"rendered":"Recheio de Abacaxi"},"content":{"rendered":"","protected":false},"featured_media":2169,"template":"","categorias_produtos":[63,102],"class_list":["post-2159","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categorias_produtos-food-service","categorias_produtos-recheios-frutas-forneaveis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recheio de Abacaxi - Bom Princ\u00edpio Alimentos<\/title>\n<meta name=\"description\" content=\"Delicie seus clientes com o aut\u00eantico sabor de abacaxi em bolos, tortas e salgados. Nosso recheio forne\u00e1vel \u00e9 resistente ao calor, f\u00e1cil de aplicar e perfeito para uso comercial. Eleva a qualidade das suas receitas e conquista paladares!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bomprincipioalimentos.com.br\/site\/produtos\/recheio-de-abacaxi\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recheio de Abacaxi - Bom Princ\u00edpio Alimentos\" \/>\n<meta property=\"og:description\" content=\"Delicie seus clientes com o aut\u00eantico sabor de abacaxi em bolos, tortas e salgados. Nosso recheio forne\u00e1vel \u00e9 resistente ao calor, f\u00e1cil de aplicar e perfeito para uso comercial. Eleva a qualidade das suas receitas e conquista paladares!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bomprincipioalimentos.com.br\/site\/produtos\/recheio-de-abacaxi\/\" \/>\n<meta property=\"og:site_name\" content=\"Bom Princ\u00edpio Alimentos\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-05T20:18:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bomprincipioalimentos.com.br\/site\/wp-content\/uploads\/2024\/12\/00134_bp_rech_abacaxiforn_1010g_img_01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"414\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/produtos\\\/recheio-de-abacaxi\\\/\",\"url\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/produtos\\\/recheio-de-abacaxi\\\/\",\"name\":\"Recheio de Abacaxi - Bom Princ\u00edpio Alimentos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/produtos\\\/recheio-de-abacaxi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/produtos\\\/recheio-de-abacaxi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/00134_bp_rech_abacaxiforn_1010g_img_01.png\",\"datePublished\":\"2024-12-06T18:46:28+00:00\",\"dateModified\":\"2025-03-05T20:18:25+00:00\",\"description\":\"Delicie seus clientes com o aut\u00eantico sabor de abacaxi em bolos, tortas e salgados. Nosso recheio forne\u00e1vel \u00e9 resistente ao calor, f\u00e1cil de aplicar e perfeito para uso comercial. Eleva a qualidade das suas receitas e conquista paladares!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/produtos\\\/recheio-de-abacaxi\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/produtos\\\/recheio-de-abacaxi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/produtos\\\/recheio-de-abacaxi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/00134_bp_rech_abacaxiforn_1010g_img_01.png\",\"contentUrl\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/00134_bp_rech_abacaxiforn_1010g_img_01.png\",\"width\":414,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/produtos\\\/recheio-de-abacaxi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recheio de Abacaxi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/\",\"name\":\"Bom Princ\u00edpio Alimentos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/#organization\",\"name\":\"Bom Princ\u00edpio Alimentos\",\"url\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-footer-bom-principio-alimentos.webp\",\"contentUrl\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-footer-bom-principio-alimentos.webp\",\"width\":561,\"height\":231,\"caption\":\"Bom Princ\u00edpio Alimentos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bomprincipioalimentos.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recheio de Abacaxi - Bom Princ\u00edpio Alimentos","description":"Delicie seus clientes com o aut\u00eantico sabor de abacaxi em bolos, tortas e salgados. Nosso recheio forne\u00e1vel \u00e9 resistente ao calor, f\u00e1cil de aplicar e perfeito para uso comercial. Eleva a qualidade das suas receitas e conquista paladares!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bomprincipioalimentos.com.br\/site\/produtos\/recheio-de-abacaxi\/","og_locale":"pt_BR","og_type":"article","og_title":"Recheio de Abacaxi - Bom Princ\u00edpio Alimentos","og_description":"Delicie seus clientes com o aut\u00eantico sabor de abacaxi em bolos, tortas e salgados. Nosso recheio forne\u00e1vel \u00e9 resistente ao calor, f\u00e1cil de aplicar e perfeito para uso comercial. Eleva a qualidade das suas receitas e conquista paladares!","og_url":"https:\/\/www.bomprincipioalimentos.com.br\/site\/produtos\/recheio-de-abacaxi\/","og_site_name":"Bom Princ\u00edpio Alimentos","article_modified_time":"2025-03-05T20:18:25+00:00","og_image":[{"width":414,"height":800,"url":"https:\/\/www.bomprincipioalimentos.com.br\/site\/wp-content\/uploads\/2024\/12\/00134_bp_rech_abacaxiforn_1010g_img_01.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bomprincipioalimentos.com.br\/site\/produtos\/recheio-de-abacaxi\/","url":"https:\/\/www.bomprincipioalimentos.com.br\/site\/produtos\/recheio-de-abacaxi\/","name":"Recheio de Abacaxi - Bom Princ\u00edpio Alimentos","isPartOf":{"@id":"https:\/\/www.bomprincipioalimentos.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bomprincipioalimentos.com.br\/site\/produtos\/recheio-de-abacaxi\/#primaryimage"},"image":{"@id":"https:\/\/www.bomprincipioalimentos.com.br\/site\/produtos\/recheio-de-abacaxi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bomprincipioalimentos.com.br\/site\/wp-content\/uploads\/2024\/12\/00134_bp_rech_abacaxiforn_1010g_img_01.png","datePublished":"2024-12-06T18:46:28+00:00","dateModified":"2025-03-05T20:18:25+00:00","description":"Delicie seus clientes com o aut\u00eantico sabor de abacaxi em bolos, tortas e salgados. Nosso recheio forne\u00e1vel \u00e9 resistente ao calor, f\u00e1cil de aplicar e perfeito para uso comercial. Eleva a qualidade das suas receitas e conquista paladares!","breadcrumb":{"@id":"https:\/\/www.bomprincipioalimentos.com.br\/site\/produtos\/recheio-de-abacaxi\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bomprincipioalimentos.com.br\/site\/produtos\/recheio-de-abacaxi\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.bomprincipioalimentos.com.br\/site\/produtos\/recheio-de-abacaxi\/#primaryimage","url":"https:\/\/www.bomprincipioalimentos.com.br\/site\/wp-content\/uploads\/2024\/12\/00134_bp_rech_abacaxiforn_1010g_img_01.png","contentUrl":"https:\/\/www.bomprincipioalimentos.com.br\/site\/wp-content\/uploads\/2024\/12\/00134_bp_rech_abacaxiforn_1010g_img_01.png","width":414,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.bomprincipioalimentos.com.br\/site\/produtos\/recheio-de-abacaxi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.bomprincipioalimentos.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Recheio de Abacaxi"}]},{"@type":"WebSite","@id":"https:\/\/www.bomprincipioalimentos.com.br\/site\/#website","url":"https:\/\/www.bomprincipioalimentos.com.br\/site\/","name":"Bom Princ\u00edpio Alimentos","description":"","publisher":{"@id":"https:\/\/www.bomprincipioalimentos.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bomprincipioalimentos.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.bomprincipioalimentos.com.br\/site\/#organization","name":"Bom Princ\u00edpio Alimentos","url":"https:\/\/www.bomprincipioalimentos.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.bomprincipioalimentos.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.bomprincipioalimentos.com.br\/site\/wp-content\/uploads\/2024\/11\/logo-footer-bom-principio-alimentos.webp","contentUrl":"https:\/\/www.bomprincipioalimentos.com.br\/site\/wp-content\/uploads\/2024\/11\/logo-footer-bom-principio-alimentos.webp","width":561,"height":231,"caption":"Bom Princ\u00edpio Alimentos"},"image":{"@id":"https:\/\/www.bomprincipioalimentos.com.br\/site\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.bomprincipioalimentos.com.br\/site\/wp-json\/wp\/v2\/produtos\/2159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bomprincipioalimentos.com.br\/site\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/www.bomprincipioalimentos.com.br\/site\/wp-json\/wp\/v2\/types\/produtos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bomprincipioalimentos.com.br\/site\/wp-json\/wp\/v2\/media\/2169"}],"wp:attachment":[{"href":"https:\/\/www.bomprincipioalimentos.com.br\/site\/wp-json\/wp\/v2\/media?parent=2159"}],"wp:term":[{"taxonomy":"categorias_produtos","embeddable":true,"href":"https:\/\/www.bomprincipioalimentos.com.br\/site\/wp-json\/wp\/v2\/categorias_produtos?post=2159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}